{"id":297,"date":"2014-04-28T11:27:35","date_gmt":"2014-04-28T08:27:35","guid":{"rendered":"http:\/\/joelahtmekultuur.ee\/neemerahvamaja\/wp-content\/uploads\/sites\/3\/2014\/04\/teaterNeemes_013.jpg"},"modified":"2014-04-28T11:27:35","modified_gmt":"2014-04-28T08:27:35","slug":"teaterneemes_013","status":"inherit","type":"attachment","link":"http:\/\/joelahtmekultuur.ee\/neemerahvamaja\/pildigalerii\/pilte-uritustelt-2013\/teaterneemes_013\/","title":{"rendered":"teaterNeemes_013"},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","template":"","meta":{"ngg_post_thumbnail":0},"class_list":["post-297","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<div class=\"attachment\"><a href='http:\/\/joelahtmekultuur.ee\/neemerahvamaja\/wp-content\/uploads\/sites\/3\/2014\/04\/teaterNeemes_013.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"450\" src=\"http:\/\/joelahtmekultuur.ee\/neemerahvamaja\/wp-content\/uploads\/sites\/3\/2014\/04\/teaterNeemes_013.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"http:\/\/joelahtmekultuur.ee\/neemerahvamaja\/wp-content\/uploads\/sites\/3\/2014\/04\/teaterNeemes_013.jpg 600w, http:\/\/joelahtmekultuur.ee\/neemerahvamaja\/wp-content\/uploads\/sites\/3\/2014\/04\/teaterNeemes_013-300x225.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><p class=\"wp-caption-text\">Teater<\/p><\/div>\n"},"caption":{"rendered":"<p>Teater<\/p>\n"},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":600,"height":450,"file":"2014\/04\/teaterNeemes_013.jpg","sizes":{"thumbnail":{"file":"teaterNeemes_013-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"http:\/\/joelahtmekultuur.ee\/neemerahvamaja\/wp-content\/uploads\/sites\/3\/2014\/04\/teaterNeemes_013-150x150.jpg"},"medium":{"file":"teaterNeemes_013-300x225.jpg","width":300,"height":225,"mime_type":"image\/jpeg","source_url":"http:\/\/joelahtmekultuur.ee\/neemerahvamaja\/wp-content\/uploads\/sites\/3\/2014\/04\/teaterNeemes_013-300x225.jpg"},"thumb-200x120":{"file":"teaterNeemes_013-200x120.jpg","width":200,"height":120,"mime_type":"image\/jpeg","source_url":"http:\/\/joelahtmekultuur.ee\/neemerahvamaja\/wp-content\/uploads\/sites\/3\/2014\/04\/teaterNeemes_013-200x120.jpg"},"full":{"file":"teaterNeemes_013.jpg","width":600,"height":450,"mime_type":"image\/jpeg","source_url":"http:\/\/joelahtmekultuur.ee\/neemerahvamaja\/wp-content\/uploads\/sites\/3\/2014\/04\/teaterNeemes_013.jpg"}},"image_meta":{"aperture":0,"credit":"","camera":"","caption":"","created_timestamp":0,"copyright":"","focal_length":0,"iso":0,"shutter_speed":0,"title":""}},"post":291,"source_url":"http:\/\/joelahtmekultuur.ee\/neemerahvamaja\/wp-content\/uploads\/sites\/3\/2014\/04\/teaterNeemes_013.jpg","_links":{"self":[{"href":"http:\/\/joelahtmekultuur.ee\/neemerahvamaja\/wp-json\/wp\/v2\/media\/297","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/joelahtmekultuur.ee\/neemerahvamaja\/wp-json\/wp\/v2\/media"}],"about":[{"href":"http:\/\/joelahtmekultuur.ee\/neemerahvamaja\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"http:\/\/joelahtmekultuur.ee\/neemerahvamaja\/wp-json\/wp\/v2\/users\/1"}],"wp:attached-to":[{"embeddable":true,"post_type":"page","id":291,"href":"http:\/\/joelahtmekultuur.ee\/neemerahvamaja\/wp-json\/wp\/v2\/pages\/291"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}